{"id":194,"date":"2019-01-23T19:25:37","date_gmt":"2019-01-23T19:25:37","guid":{"rendered":"http:\/\/mrsdprojects.ri.cmu.edu\/2018teami\/?page_id=194"},"modified":"2019-02-22T01:57:08","modified_gmt":"2019-02-22T01:57:08","slug":"parts-list","status":"publish","type":"page","link":"https:\/\/mrsdprojects.ri.cmu.edu\/2018teami\/parts-list\/","title":{"rendered":"Parts List"},"content":{"rendered":"\n<table id=\"tablepress-8\" class=\"tablepress tablepress-id-8\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Components<\/th><th class=\"column-2\">Type<\/th><th class=\"column-3\">Alternative<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Mobile Platform<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Chassis<\/td><td class=\"column-2\">Slotted Aluminum Extension <\/td><td class=\"column-3\">Machined<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Actuators<\/td><td class=\"column-2\">DC motor <\/td><td class=\"column-3\">Dynamixel MX-106T<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Wheel<\/td><td class=\"column-2\">Foam Type <\/td><td class=\"column-3\"><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Motor controller<\/td><td class=\"column-2\">High Discharge <\/td><td class=\"column-3\">Roboclaw 40A<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">DC-DC Converter<\/td><td class=\"column-2\">24V to 13.8V <\/td><td class=\"column-3\">Meccanixity DC-DC<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Processor<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">Intel NUC <\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Controllers<\/td><td class=\"column-2\">Gaming Console <\/td><td class=\"column-3\">Sony Dual Shock 4 <\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">LiPo Battery<br \/>\nCharger <\/td><td class=\"column-2\">8s Battery Charger<\/td><td class=\"column-3\">HTRC 1200W <\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Kill Switch <\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Controller to PC Adapter <\/td><td class=\"column-2\">USB Wireless<\/td><td class=\"column-3\">Sony Dual Shock 4<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Battery<\/td><td class=\"column-2\">22.2V, 16 Ah LiPo<\/td><td class=\"column-3\">Multi Star LiPo <\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">Sensing and Communication <\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">Wi-Fi<br \/>\nCommunication<br \/>\nModule <\/td><td class=\"column-2\">Wi-Fi Router<\/td><td class=\"column-3\">TP Link Archer C50<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">RTK<\/td><td class=\"column-2\">GNSS<\/td><td class=\"column-3\">Piksi Multi GNSS Module <\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">Camera<\/td><td class=\"column-2\">Catadioptric <\/td><td class=\"column-3\">Arducam 8MP Sony IMX219 <\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">Ultra-wide band<br \/>\ntags<\/td><td class=\"column-2\">Time of flight sensors<\/td><td class=\"column-3\">DecaWave Dev-Kit <\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">IMU <\/td><td class=\"column-2\">Tri-axial <\/td><td class=\"column-3\">Sparkle Fun <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-8 from cache -->\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":175,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-194","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mrsdprojects.ri.cmu.edu\/2018teami\/wp-json\/wp\/v2\/pages\/194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrsdprojects.ri.cmu.edu\/2018teami\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mrsdprojects.ri.cmu.edu\/2018teami\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mrsdprojects.ri.cmu.edu\/2018teami\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/mrsdprojects.ri.cmu.edu\/2018teami\/wp-json\/wp\/v2\/comments?post=194"}],"version-history":[{"count":2,"href":"https:\/\/mrsdprojects.ri.cmu.edu\/2018teami\/wp-json\/wp\/v2\/pages\/194\/revisions"}],"predecessor-version":[{"id":277,"href":"https:\/\/mrsdprojects.ri.cmu.edu\/2018teami\/wp-json\/wp\/v2\/pages\/194\/revisions\/277"}],"wp:attachment":[{"href":"https:\/\/mrsdprojects.ri.cmu.edu\/2018teami\/wp-json\/wp\/v2\/media?parent=194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}